{"id":57915,"date":"2025-12-15T00:26:04","date_gmt":"2025-12-14T23:26:04","guid":{"rendered":"https:\/\/www.koonings.com\/product\/enzoani-blue-collection-rhapsody-l\/"},"modified":"2026-02-03T18:30:33","modified_gmt":"2026-02-03T17:30:33","slug":"enzoani-blue-collection-rhapsody-l","status":"publish","type":"product","link":"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/","title":{"rendered":"Enzoani Blaue Kollektion Rhapsody-L"},"content":{"rendered":"<p>Wir sind von dieser A-Linien-Sch\u00f6nheit begeistert! Von der pr\u00e4chtigen botanischen Spitze mit Perlen bis hin zum wundersch\u00f6nen Rock aus Glitzert\u00fcll &#8211; dieses Kleid ist ein absolutes Highlight. Der tiefe V-Ausschnitt und der hohe Schlitz an der Vorderseite vervollst\u00e4ndigen diesen glamour\u00f6sen Look.  <\/p>\n","protected":false},"featured_media":42069,"template":"","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":""},"productdetails":[379,376,383,378],"productneck":[356],"productcolor":[393,392],"maat":[],"productsupplier":[405],"productsleeve":[359],"productcategory":[18],"productsilhouette":[384],"productstyle":[372,366,370],"class_list":["post-57915","product","type-product","status-publish","has-post-thumbnail","hentry","productdetails-379","productdetails-376","productdetails-383","productdetails-378","productneck-356","productcolor-393","productcolor-392","productsupplier-enzoani-blue-collection","productsleeve-359","productcategory-trouwjurken","productsilhouette-384","productstyle-372","productstyle-366","productstyle-370"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enzoani Blaue Kollektion Rhapsody-L | Koonings<\/title>\n<meta name=\"description\" content=\"Wir sind von dieser A-Linien-Sch\u00f6nheit begeistert! Von der pr\u00e4chtigen botanischen Spitze mit Perlen bis hin zum wundersch\u00f6nen Rock aus Glitzert\u00fcll - dieses Kleid ist ein absolutes Highlight. Der tiefe V-Ausschnitt und der hohe Schlitz an der Vorderseite vervollst\u00e4ndigen diesen glamour\u00f6sen Look.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enzoani Blaue Kollektion Rhapsody-L | Koonings\" \/>\n<meta property=\"og:description\" content=\"Wir sind von dieser A-Linien-Sch\u00f6nheit begeistert! Von der pr\u00e4chtigen botanischen Spitze mit Perlen bis hin zum wundersch\u00f6nen Rock aus Glitzert\u00fcll - dieses Kleid ist ein absolutes Highlight. Der tiefe V-Ausschnitt und der hohe Schlitz an der Vorderseite vervollst\u00e4ndigen diesen glamour\u00f6sen Look.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/\" \/>\n<meta property=\"og:site_name\" content=\"Koonings\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kooningstheweddingpalace\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T17:30:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/11\/39707_11d421cd609a847d2e9401473a4c6cb133d0338fd9970ab33af4ced82ea25897a17b217b.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1035\" \/>\n\t<meta property=\"og:image:height\" content=\"1380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/enzoani-blue-collection-rhapsody-l\\\/\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/enzoani-blue-collection-rhapsody-l\\\/\",\"name\":\"Enzoani Blaue Kollektion Rhapsody-L | Koonings\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/enzoani-blue-collection-rhapsody-l\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/enzoani-blue-collection-rhapsody-l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/39707_11d421cd609a847d2e9401473a4c6cb133d0338fd9970ab33af4ced82ea25897a17b217b.jpeg\",\"datePublished\":\"2025-12-14T23:26:04+00:00\",\"dateModified\":\"2026-02-03T17:30:33+00:00\",\"description\":\"Wir sind von dieser A-Linien-Sch\u00f6nheit begeistert! Von der pr\u00e4chtigen botanischen Spitze mit Perlen bis hin zum wundersch\u00f6nen Rock aus Glitzert\u00fcll - dieses Kleid ist ein absolutes Highlight. Der tiefe V-Ausschnitt und der hohe Schlitz an der Vorderseite vervollst\u00e4ndigen diesen glamour\u00f6sen Look.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/enzoani-blue-collection-rhapsody-l\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/enzoani-blue-collection-rhapsody-l\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/enzoani-blue-collection-rhapsody-l\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/39707_11d421cd609a847d2e9401473a4c6cb133d0338fd9970ab33af4ced82ea25897a17b217b.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/39707_11d421cd609a847d2e9401473a4c6cb133d0338fd9970ab33af4ced82ea25897a17b217b.jpeg\",\"width\":1035,\"height\":1380},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/enzoani-blue-collection-rhapsody-l\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enzoani Blaue Kollektion Rhapsody-L\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/\",\"name\":\"Koonings\",\"description\":\"De grootste bruidsmodewinkel ter wereld\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#organization\",\"name\":\"Koonings\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo.png\",\"width\":600,\"height\":428,\"caption\":\"Koonings\"},\"image\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kooningstheweddingpalace\",\"https:\\\/\\\/www.instagram.com\\\/kooningstheweddingpalace\",\"https:\\\/\\\/www.pinterest.com\\\/koonings\",\"https:\\\/\\\/www.youtube.com\\\/kooningstheweddingpalace\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enzoani Blaue Kollektion Rhapsody-L | Koonings","description":"Wir sind von dieser A-Linien-Sch\u00f6nheit begeistert! Von der pr\u00e4chtigen botanischen Spitze mit Perlen bis hin zum wundersch\u00f6nen Rock aus Glitzert\u00fcll - dieses Kleid ist ein absolutes Highlight. Der tiefe V-Ausschnitt und der hohe Schlitz an der Vorderseite vervollst\u00e4ndigen diesen glamour\u00f6sen Look.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/","og_locale":"de_DE","og_type":"article","og_title":"Enzoani Blaue Kollektion Rhapsody-L | Koonings","og_description":"Wir sind von dieser A-Linien-Sch\u00f6nheit begeistert! Von der pr\u00e4chtigen botanischen Spitze mit Perlen bis hin zum wundersch\u00f6nen Rock aus Glitzert\u00fcll - dieses Kleid ist ein absolutes Highlight. Der tiefe V-Ausschnitt und der hohe Schlitz an der Vorderseite vervollst\u00e4ndigen diesen glamour\u00f6sen Look.","og_url":"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/","og_site_name":"Koonings","article_publisher":"https:\/\/www.facebook.com\/kooningstheweddingpalace","article_modified_time":"2026-02-03T17:30:33+00:00","og_image":[{"width":1035,"height":1380,"url":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/11\/39707_11d421cd609a847d2e9401473a4c6cb133d0338fd9970ab33af4ced82ea25897a17b217b.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/","url":"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/","name":"Enzoani Blaue Kollektion Rhapsody-L | Koonings","isPartOf":{"@id":"https:\/\/www.koonings.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/#primaryimage"},"image":{"@id":"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/#primaryimage"},"thumbnailUrl":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/11\/39707_11d421cd609a847d2e9401473a4c6cb133d0338fd9970ab33af4ced82ea25897a17b217b.jpeg","datePublished":"2025-12-14T23:26:04+00:00","dateModified":"2026-02-03T17:30:33+00:00","description":"Wir sind von dieser A-Linien-Sch\u00f6nheit begeistert! Von der pr\u00e4chtigen botanischen Spitze mit Perlen bis hin zum wundersch\u00f6nen Rock aus Glitzert\u00fcll - dieses Kleid ist ein absolutes Highlight. Der tiefe V-Ausschnitt und der hohe Schlitz an der Vorderseite vervollst\u00e4ndigen diesen glamour\u00f6sen Look.","breadcrumb":{"@id":"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/#primaryimage","url":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/11\/39707_11d421cd609a847d2e9401473a4c6cb133d0338fd9970ab33af4ced82ea25897a17b217b.jpeg","contentUrl":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/11\/39707_11d421cd609a847d2e9401473a4c6cb133d0338fd9970ab33af4ced82ea25897a17b217b.jpeg","width":1035,"height":1380},{"@type":"BreadcrumbList","@id":"https:\/\/www.koonings.com\/de\/product\/enzoani-blue-collection-rhapsody-l\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.koonings.com\/de\/"},{"@type":"ListItem","position":2,"name":"Enzoani Blaue Kollektion Rhapsody-L"}]},{"@type":"WebSite","@id":"https:\/\/www.koonings.com\/de\/#website","url":"https:\/\/www.koonings.com\/de\/","name":"Koonings","description":"De grootste bruidsmodewinkel ter wereld","publisher":{"@id":"https:\/\/www.koonings.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.koonings.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.koonings.com\/de\/#organization","name":"Koonings","url":"https:\/\/www.koonings.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.koonings.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/07\/logo.png","contentUrl":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/07\/logo.png","width":600,"height":428,"caption":"Koonings"},"image":{"@id":"https:\/\/www.koonings.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kooningstheweddingpalace","https:\/\/www.instagram.com\/kooningstheweddingpalace","https:\/\/www.pinterest.com\/koonings","https:\/\/www.youtube.com\/kooningstheweddingpalace"]}]}},"_links":{"self":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/product\/57915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/media\/42069"}],"wp:attachment":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/media?parent=57915"}],"wp:term":[{"taxonomy":"productdetails","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productdetails?post=57915"},{"taxonomy":"productneck","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productneck?post=57915"},{"taxonomy":"productcolor","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productcolor?post=57915"},{"taxonomy":"maat","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/maat?post=57915"},{"taxonomy":"productsupplier","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productsupplier?post=57915"},{"taxonomy":"productsleeve","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productsleeve?post=57915"},{"taxonomy":"productcategory","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productcategory?post=57915"},{"taxonomy":"productsilhouette","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productsilhouette?post=57915"},{"taxonomy":"productstyle","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productstyle?post=57915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}