{"id":56763,"date":"2025-12-15T00:12:41","date_gmt":"2025-12-14T23:12:41","guid":{"rendered":"https:\/\/www.koonings.com\/product\/elysee-lakme-l\/"},"modified":"2026-02-03T18:04:09","modified_gmt":"2026-02-03T17:04:09","slug":"elysee-lakme-l","status":"publish","type":"product","link":"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/","title":{"rendered":"Elysee Lakme-L"},"content":{"rendered":"<p>Mit dem Hochzeitskleid von Lakm\u00e9 werden Sie sich zweifellos wie eine G\u00f6ttin f\u00fchlen und aussehen. Der klassisch geschwungene Ausschnitt mit den einzigartigen schulterfreien Tr\u00e4gern und dem hohen Korsett im R\u00fccken ist perfekt dezent und doch kokett. Dieses glitzernde Kleid aus Chantilly-Spitze hat seitliche Illusionsausschnitte, die die Figur auf nat\u00fcrliche Weise konturieren und umschmeicheln, w\u00e4hrend der doppelt geschwungene Saum des eleganten \u00c9lys\u00e9e-Kleides alle Blicke auf sich ziehen wird.  <\/p>\n","protected":false},"featured_media":34350,"template":"","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":""},"productdetails":[379,376,381],"productneck":[349],"productcolor":[393,392],"maat":[],"productsupplier":[427],"productsleeve":[363],"productcategory":[18],"productsilhouette":[387,390],"productstyle":[366,370],"class_list":["post-56763","product","type-product","status-publish","has-post-thumbnail","hentry","productdetails-379","productdetails-376","productdetails-381","productneck-349","productcolor-393","productcolor-392","productsupplier-elysee","productsleeve-363","productcategory-trouwjurken","productsilhouette-387","productsilhouette-390","productstyle-366","productstyle-370"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elysee Lakme-L | Koonings<\/title>\n<meta name=\"description\" content=\"Mit dem Hochzeitskleid von Lakm\u00e9 werden Sie sich zweifellos wie eine G\u00f6ttin f\u00fchlen und aussehen. Der klassisch geschwungene Ausschnitt mit den einzigartigen schulterfreien Tr\u00e4gern und dem hohen Korsett im R\u00fccken ist perfekt dezent und doch kokett. Dieses glitzernde Kleid aus Chantilly-Spitze hat seitliche Illusionsausschnitte, die die Figur auf nat\u00fcrliche Weise konturieren und umschmeicheln, w\u00e4hrend der doppelt geschwungene Saum des eleganten \u00c9lys\u00e9e-Kleides alle Blicke auf sich ziehen wird.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elysee Lakme-L | Koonings\" \/>\n<meta property=\"og:description\" content=\"Mit dem Hochzeitskleid von Lakm\u00e9 werden Sie sich zweifellos wie eine G\u00f6ttin f\u00fchlen und aussehen. Der klassisch geschwungene Ausschnitt mit den einzigartigen schulterfreien Tr\u00e4gern und dem hohen Korsett im R\u00fccken ist perfekt dezent und doch kokett. Dieses glitzernde Kleid aus Chantilly-Spitze hat seitliche Illusionsausschnitte, die die Figur auf nat\u00fcrliche Weise konturieren und umschmeicheln, w\u00e4hrend der doppelt geschwungene Saum des eleganten \u00c9lys\u00e9e-Kleides alle Blicke auf sich ziehen wird.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/\" \/>\n<meta property=\"og:site_name\" content=\"Koonings\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kooningstheweddingpalace\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T17:04:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/11\/37920_dd9b7ffb0a5c42a204b2194336c66d77c211abd5f9792e37422a368e44aa66e5d134afad.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1035\" \/>\n\t<meta property=\"og:image:height\" content=\"1380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/elysee-lakme-l\\\/\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/elysee-lakme-l\\\/\",\"name\":\"Elysee Lakme-L | Koonings\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/elysee-lakme-l\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/elysee-lakme-l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/37920_dd9b7ffb0a5c42a204b2194336c66d77c211abd5f9792e37422a368e44aa66e5d134afad.jpeg\",\"datePublished\":\"2025-12-14T23:12:41+00:00\",\"dateModified\":\"2026-02-03T17:04:09+00:00\",\"description\":\"Mit dem Hochzeitskleid von Lakm\u00e9 werden Sie sich zweifellos wie eine G\u00f6ttin f\u00fchlen und aussehen. Der klassisch geschwungene Ausschnitt mit den einzigartigen schulterfreien Tr\u00e4gern und dem hohen Korsett im R\u00fccken ist perfekt dezent und doch kokett. Dieses glitzernde Kleid aus Chantilly-Spitze hat seitliche Illusionsausschnitte, die die Figur auf nat\u00fcrliche Weise konturieren und umschmeicheln, w\u00e4hrend der doppelt geschwungene Saum des eleganten \u00c9lys\u00e9e-Kleides alle Blicke auf sich ziehen wird.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/elysee-lakme-l\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/elysee-lakme-l\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/elysee-lakme-l\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/37920_dd9b7ffb0a5c42a204b2194336c66d77c211abd5f9792e37422a368e44aa66e5d134afad.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/37920_dd9b7ffb0a5c42a204b2194336c66d77c211abd5f9792e37422a368e44aa66e5d134afad.jpeg\",\"width\":1035,\"height\":1380},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/elysee-lakme-l\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elysee Lakme-L\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/\",\"name\":\"Koonings\",\"description\":\"De grootste bruidsmodewinkel ter wereld\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#organization\",\"name\":\"Koonings\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo.png\",\"width\":600,\"height\":428,\"caption\":\"Koonings\"},\"image\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kooningstheweddingpalace\",\"https:\\\/\\\/www.instagram.com\\\/kooningstheweddingpalace\",\"https:\\\/\\\/www.pinterest.com\\\/koonings\",\"https:\\\/\\\/www.youtube.com\\\/kooningstheweddingpalace\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elysee Lakme-L | Koonings","description":"Mit dem Hochzeitskleid von Lakm\u00e9 werden Sie sich zweifellos wie eine G\u00f6ttin f\u00fchlen und aussehen. Der klassisch geschwungene Ausschnitt mit den einzigartigen schulterfreien Tr\u00e4gern und dem hohen Korsett im R\u00fccken ist perfekt dezent und doch kokett. Dieses glitzernde Kleid aus Chantilly-Spitze hat seitliche Illusionsausschnitte, die die Figur auf nat\u00fcrliche Weise konturieren und umschmeicheln, w\u00e4hrend der doppelt geschwungene Saum des eleganten \u00c9lys\u00e9e-Kleides alle Blicke auf sich ziehen wird.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/","og_locale":"de_DE","og_type":"article","og_title":"Elysee Lakme-L | Koonings","og_description":"Mit dem Hochzeitskleid von Lakm\u00e9 werden Sie sich zweifellos wie eine G\u00f6ttin f\u00fchlen und aussehen. Der klassisch geschwungene Ausschnitt mit den einzigartigen schulterfreien Tr\u00e4gern und dem hohen Korsett im R\u00fccken ist perfekt dezent und doch kokett. Dieses glitzernde Kleid aus Chantilly-Spitze hat seitliche Illusionsausschnitte, die die Figur auf nat\u00fcrliche Weise konturieren und umschmeicheln, w\u00e4hrend der doppelt geschwungene Saum des eleganten \u00c9lys\u00e9e-Kleides alle Blicke auf sich ziehen wird.","og_url":"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/","og_site_name":"Koonings","article_publisher":"https:\/\/www.facebook.com\/kooningstheweddingpalace","article_modified_time":"2026-02-03T17:04:09+00:00","og_image":[{"width":1035,"height":1380,"url":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/11\/37920_dd9b7ffb0a5c42a204b2194336c66d77c211abd5f9792e37422a368e44aa66e5d134afad.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/","url":"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/","name":"Elysee Lakme-L | Koonings","isPartOf":{"@id":"https:\/\/www.koonings.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/#primaryimage"},"image":{"@id":"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/#primaryimage"},"thumbnailUrl":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/11\/37920_dd9b7ffb0a5c42a204b2194336c66d77c211abd5f9792e37422a368e44aa66e5d134afad.jpeg","datePublished":"2025-12-14T23:12:41+00:00","dateModified":"2026-02-03T17:04:09+00:00","description":"Mit dem Hochzeitskleid von Lakm\u00e9 werden Sie sich zweifellos wie eine G\u00f6ttin f\u00fchlen und aussehen. Der klassisch geschwungene Ausschnitt mit den einzigartigen schulterfreien Tr\u00e4gern und dem hohen Korsett im R\u00fccken ist perfekt dezent und doch kokett. Dieses glitzernde Kleid aus Chantilly-Spitze hat seitliche Illusionsausschnitte, die die Figur auf nat\u00fcrliche Weise konturieren und umschmeicheln, w\u00e4hrend der doppelt geschwungene Saum des eleganten \u00c9lys\u00e9e-Kleides alle Blicke auf sich ziehen wird.","breadcrumb":{"@id":"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/#primaryimage","url":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/11\/37920_dd9b7ffb0a5c42a204b2194336c66d77c211abd5f9792e37422a368e44aa66e5d134afad.jpeg","contentUrl":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/11\/37920_dd9b7ffb0a5c42a204b2194336c66d77c211abd5f9792e37422a368e44aa66e5d134afad.jpeg","width":1035,"height":1380},{"@type":"BreadcrumbList","@id":"https:\/\/www.koonings.com\/de\/product\/elysee-lakme-l\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.koonings.com\/de\/"},{"@type":"ListItem","position":2,"name":"Elysee Lakme-L"}]},{"@type":"WebSite","@id":"https:\/\/www.koonings.com\/de\/#website","url":"https:\/\/www.koonings.com\/de\/","name":"Koonings","description":"De grootste bruidsmodewinkel ter wereld","publisher":{"@id":"https:\/\/www.koonings.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.koonings.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.koonings.com\/de\/#organization","name":"Koonings","url":"https:\/\/www.koonings.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.koonings.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/07\/logo.png","contentUrl":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/07\/logo.png","width":600,"height":428,"caption":"Koonings"},"image":{"@id":"https:\/\/www.koonings.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kooningstheweddingpalace","https:\/\/www.instagram.com\/kooningstheweddingpalace","https:\/\/www.pinterest.com\/koonings","https:\/\/www.youtube.com\/kooningstheweddingpalace"]}]}},"_links":{"self":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/product\/56763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/media\/34350"}],"wp:attachment":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/media?parent=56763"}],"wp:term":[{"taxonomy":"productdetails","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productdetails?post=56763"},{"taxonomy":"productneck","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productneck?post=56763"},{"taxonomy":"productcolor","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productcolor?post=56763"},{"taxonomy":"maat","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/maat?post=56763"},{"taxonomy":"productsupplier","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productsupplier?post=56763"},{"taxonomy":"productsleeve","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productsleeve?post=56763"},{"taxonomy":"productcategory","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productcategory?post=56763"},{"taxonomy":"productsilhouette","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productsilhouette?post=56763"},{"taxonomy":"productstyle","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productstyle?post=56763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}