{"id":108449,"date":"2026-06-30T14:34:12","date_gmt":"2026-06-30T12:34:12","guid":{"rendered":"https:\/\/www.koonings.com\/product\/modeca-genesis\/"},"modified":"2026-06-19T15:14:59","modified_gmt":"2026-06-19T13:14:59","slug":"modeca-genesis","status":"publish","type":"product","link":"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/","title":{"rendered":"Modeca Genesis"},"content":{"rendered":"<p>\u201eGenesis\u201c ist ein Fit-and-Flare-Kleid aus Mikado, das modernen und klassischen Stil m\u00fchelos vereint und pure, zeitlose Eleganz ausstrahlt. Der umgeschlagene Ausschnitt verleiht dem Kleid eine raffinierte Note, w\u00e4hrend die strukturierte Silhouette Ihre Kurven wundersch\u00f6n betont. Eine gro\u00dfe Schleife am R\u00fccken sorgt f\u00fcr einen echten Blickfang, wenn Sie den Gang entlangschreiten, und sorgt f\u00fcr die perfekte Mischung aus Romantik und Dramatik. F\u00fcr Br\u00e4ute, die einen eher minimalistischen Look bevorzugen, gibt es das Modell Genesis-D ohne Schleife. Ganz gleich, f\u00fcr welche Variante Du dich entscheidest \u2013 dieses Kleid ist Liebe auf den ersten Blick!<br \/>\nErleben Sie den Zauber von Genesis und entdecken Sie die gesamte Kollektion bei Koonings.<\/p>\n","protected":false},"featured_media":95460,"template":"","meta":{"_acf_changed":false,"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":""},"productdetails":[378],"productneck":[354],"productcolor":[392],"maat":[],"productsupplier":[434],"productsleeve":[],"productcategory":[18],"productsilhouette":[389],"productstyle":[365,371],"class_list":["post-108449","product","type-product","status-publish","has-post-thumbnail","hentry","productdetails-378","productneck-354","productcolor-392","productsupplier-modeca","productcategory-trouwjurken","productsilhouette-389","productstyle-365","productstyle-371"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modeca Genesis | Koonings<\/title>\n<meta name=\"description\" content=\"\u201eGenesis\u201c ist ein Fit-and-Flare-Kleid aus Mikado, das modernen und klassischen Stil m\u00fchelos vereint und pure, zeitlose Eleganz ausstrahlt. Der umgeschlagene Ausschnitt verleiht dem Kleid eine raffinierte Note, w\u00e4hrend die strukturierte Silhouette Ihre Kurven wundersch\u00f6n betont. Eine gro\u00dfe Schleife am R\u00fccken sorgt f\u00fcr einen echten Blickfang, wenn Sie den Gang entlangschreiten, und sorgt f\u00fcr die perfekte Mischung aus Romantik und Dramatik. F\u00fcr Br\u00e4ute, die einen eher minimalistischen Look bevorzugen, gibt es das Modell Genesis-D ohne Schleife. Ganz gleich, f\u00fcr welche Variante Du dich entscheidest \u2013 dieses Kleid ist Liebe auf den ersten Blick! Erleben Sie den Zauber von Genesis und entdecken Sie die gesamte Kollektion bei Koonings.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modeca Genesis | Koonings\" \/>\n<meta property=\"og:description\" content=\"\u201eGenesis\u201c ist ein Fit-and-Flare-Kleid aus Mikado, das modernen und klassischen Stil m\u00fchelos vereint und pure, zeitlose Eleganz ausstrahlt. Der umgeschlagene Ausschnitt verleiht dem Kleid eine raffinierte Note, w\u00e4hrend die strukturierte Silhouette Ihre Kurven wundersch\u00f6n betont. Eine gro\u00dfe Schleife am R\u00fccken sorgt f\u00fcr einen echten Blickfang, wenn Sie den Gang entlangschreiten, und sorgt f\u00fcr die perfekte Mischung aus Romantik und Dramatik. F\u00fcr Br\u00e4ute, die einen eher minimalistischen Look bevorzugen, gibt es das Modell Genesis-D ohne Schleife. Ganz gleich, f\u00fcr welche Variante Du dich entscheidest \u2013 dieses Kleid ist Liebe auf den ersten Blick! Erleben Sie den Zauber von Genesis und entdecken Sie die gesamte Kollektion bei Koonings.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/\" \/>\n<meta property=\"og:site_name\" content=\"Koonings\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kooningstheweddingpalace\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.koonings.com\/wp-content\/uploads\/2025\/09\/51130_f30a52c9541d9f4cc3555f2a4ac911c985446ace358d15e50873b29a354ccfc9433532af.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1511\" \/>\n\t<meta property=\"og:image:height\" content=\"2135\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/modeca-genesis\\\/\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/modeca-genesis\\\/\",\"name\":\"Modeca Genesis | Koonings\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/modeca-genesis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/modeca-genesis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/51130_f30a52c9541d9f4cc3555f2a4ac911c985446ace358d15e50873b29a354ccfc9433532af.jpeg\",\"datePublished\":\"2026-06-30T12:34:12+00:00\",\"description\":\"\u201eGenesis\u201c ist ein Fit-and-Flare-Kleid aus Mikado, das modernen und klassischen Stil m\u00fchelos vereint und pure, zeitlose Eleganz ausstrahlt. Der umgeschlagene Ausschnitt verleiht dem Kleid eine raffinierte Note, w\u00e4hrend die strukturierte Silhouette Ihre Kurven wundersch\u00f6n betont. Eine gro\u00dfe Schleife am R\u00fccken sorgt f\u00fcr einen echten Blickfang, wenn Sie den Gang entlangschreiten, und sorgt f\u00fcr die perfekte Mischung aus Romantik und Dramatik. F\u00fcr Br\u00e4ute, die einen eher minimalistischen Look bevorzugen, gibt es das Modell Genesis-D ohne Schleife. Ganz gleich, f\u00fcr welche Variante Du dich entscheidest \u2013 dieses Kleid ist Liebe auf den ersten Blick! Erleben Sie den Zauber von Genesis und entdecken Sie die gesamte Kollektion bei Koonings.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/modeca-genesis\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/modeca-genesis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/modeca-genesis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/51130_f30a52c9541d9f4cc3555f2a4ac911c985446ace358d15e50873b29a354ccfc9433532af.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/51130_f30a52c9541d9f4cc3555f2a4ac911c985446ace358d15e50873b29a354ccfc9433532af.jpeg\",\"width\":1511,\"height\":2135},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/product\\\/modeca-genesis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modeca Genesis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/\",\"name\":\"Koonings\",\"description\":\"De grootste bruidsmodewinkel ter wereld\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#organization\",\"name\":\"Koonings\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.koonings.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo.png\",\"width\":600,\"height\":428,\"caption\":\"Koonings\"},\"image\":{\"@id\":\"https:\\\/\\\/www.koonings.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kooningstheweddingpalace\",\"https:\\\/\\\/www.instagram.com\\\/kooningstheweddingpalace\",\"https:\\\/\\\/www.pinterest.com\\\/koonings\",\"https:\\\/\\\/www.youtube.com\\\/kooningstheweddingpalace\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modeca Genesis | Koonings","description":"\u201eGenesis\u201c ist ein Fit-and-Flare-Kleid aus Mikado, das modernen und klassischen Stil m\u00fchelos vereint und pure, zeitlose Eleganz ausstrahlt. Der umgeschlagene Ausschnitt verleiht dem Kleid eine raffinierte Note, w\u00e4hrend die strukturierte Silhouette Ihre Kurven wundersch\u00f6n betont. Eine gro\u00dfe Schleife am R\u00fccken sorgt f\u00fcr einen echten Blickfang, wenn Sie den Gang entlangschreiten, und sorgt f\u00fcr die perfekte Mischung aus Romantik und Dramatik. F\u00fcr Br\u00e4ute, die einen eher minimalistischen Look bevorzugen, gibt es das Modell Genesis-D ohne Schleife. Ganz gleich, f\u00fcr welche Variante Du dich entscheidest \u2013 dieses Kleid ist Liebe auf den ersten Blick! Erleben Sie den Zauber von Genesis und entdecken Sie die gesamte Kollektion bei Koonings.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/","og_locale":"de_DE","og_type":"article","og_title":"Modeca Genesis | Koonings","og_description":"\u201eGenesis\u201c ist ein Fit-and-Flare-Kleid aus Mikado, das modernen und klassischen Stil m\u00fchelos vereint und pure, zeitlose Eleganz ausstrahlt. Der umgeschlagene Ausschnitt verleiht dem Kleid eine raffinierte Note, w\u00e4hrend die strukturierte Silhouette Ihre Kurven wundersch\u00f6n betont. Eine gro\u00dfe Schleife am R\u00fccken sorgt f\u00fcr einen echten Blickfang, wenn Sie den Gang entlangschreiten, und sorgt f\u00fcr die perfekte Mischung aus Romantik und Dramatik. F\u00fcr Br\u00e4ute, die einen eher minimalistischen Look bevorzugen, gibt es das Modell Genesis-D ohne Schleife. Ganz gleich, f\u00fcr welche Variante Du dich entscheidest \u2013 dieses Kleid ist Liebe auf den ersten Blick! Erleben Sie den Zauber von Genesis und entdecken Sie die gesamte Kollektion bei Koonings.","og_url":"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/","og_site_name":"Koonings","article_publisher":"https:\/\/www.facebook.com\/kooningstheweddingpalace","og_image":[{"width":1511,"height":2135,"url":"https:\/\/www.koonings.com\/wp-content\/uploads\/2025\/09\/51130_f30a52c9541d9f4cc3555f2a4ac911c985446ace358d15e50873b29a354ccfc9433532af.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/","url":"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/","name":"Modeca Genesis | Koonings","isPartOf":{"@id":"https:\/\/www.koonings.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/#primaryimage"},"image":{"@id":"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.koonings.com\/wp-content\/uploads\/2025\/09\/51130_f30a52c9541d9f4cc3555f2a4ac911c985446ace358d15e50873b29a354ccfc9433532af.jpeg","datePublished":"2026-06-30T12:34:12+00:00","description":"\u201eGenesis\u201c ist ein Fit-and-Flare-Kleid aus Mikado, das modernen und klassischen Stil m\u00fchelos vereint und pure, zeitlose Eleganz ausstrahlt. Der umgeschlagene Ausschnitt verleiht dem Kleid eine raffinierte Note, w\u00e4hrend die strukturierte Silhouette Ihre Kurven wundersch\u00f6n betont. Eine gro\u00dfe Schleife am R\u00fccken sorgt f\u00fcr einen echten Blickfang, wenn Sie den Gang entlangschreiten, und sorgt f\u00fcr die perfekte Mischung aus Romantik und Dramatik. F\u00fcr Br\u00e4ute, die einen eher minimalistischen Look bevorzugen, gibt es das Modell Genesis-D ohne Schleife. Ganz gleich, f\u00fcr welche Variante Du dich entscheidest \u2013 dieses Kleid ist Liebe auf den ersten Blick! Erleben Sie den Zauber von Genesis und entdecken Sie die gesamte Kollektion bei Koonings.","breadcrumb":{"@id":"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/#primaryimage","url":"https:\/\/www.koonings.com\/wp-content\/uploads\/2025\/09\/51130_f30a52c9541d9f4cc3555f2a4ac911c985446ace358d15e50873b29a354ccfc9433532af.jpeg","contentUrl":"https:\/\/www.koonings.com\/wp-content\/uploads\/2025\/09\/51130_f30a52c9541d9f4cc3555f2a4ac911c985446ace358d15e50873b29a354ccfc9433532af.jpeg","width":1511,"height":2135},{"@type":"BreadcrumbList","@id":"https:\/\/www.koonings.com\/de\/product\/modeca-genesis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.koonings.com\/de\/"},{"@type":"ListItem","position":2,"name":"Modeca Genesis"}]},{"@type":"WebSite","@id":"https:\/\/www.koonings.com\/de\/#website","url":"https:\/\/www.koonings.com\/de\/","name":"Koonings","description":"De grootste bruidsmodewinkel ter wereld","publisher":{"@id":"https:\/\/www.koonings.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.koonings.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.koonings.com\/de\/#organization","name":"Koonings","url":"https:\/\/www.koonings.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.koonings.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/07\/logo.png","contentUrl":"https:\/\/www.koonings.com\/wp-content\/uploads\/2024\/07\/logo.png","width":600,"height":428,"caption":"Koonings"},"image":{"@id":"https:\/\/www.koonings.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kooningstheweddingpalace","https:\/\/www.instagram.com\/kooningstheweddingpalace","https:\/\/www.pinterest.com\/koonings","https:\/\/www.youtube.com\/kooningstheweddingpalace"]}]}},"_links":{"self":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/product\/108449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/media\/95460"}],"wp:attachment":[{"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/media?parent=108449"}],"wp:term":[{"taxonomy":"productdetails","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productdetails?post=108449"},{"taxonomy":"productneck","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productneck?post=108449"},{"taxonomy":"productcolor","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productcolor?post=108449"},{"taxonomy":"maat","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/maat?post=108449"},{"taxonomy":"productsupplier","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productsupplier?post=108449"},{"taxonomy":"productsleeve","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productsleeve?post=108449"},{"taxonomy":"productcategory","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productcategory?post=108449"},{"taxonomy":"productsilhouette","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productsilhouette?post=108449"},{"taxonomy":"productstyle","embeddable":true,"href":"https:\/\/www.koonings.com\/de\/wp-json\/wp\/v2\/productstyle?post=108449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}